{"id":47,"date":"2021-05-04T19:05:19","date_gmt":"2021-05-04T19:05:19","guid":{"rendered":"http:\/\/class101dev.wpengine.com\/?page_id=47"},"modified":"2026-01-20T05:36:54","modified_gmt":"2026-01-20T05:36:54","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-about-us.php","meta":{"_acf_changed":true,"footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Us - Class 101 Peachtree City, GA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.class101.com\/peachtreecityga\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us - Class 101 Peachtree City, GA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.class101.com\/peachtreecityga\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Class 101 Peachtree City, GA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T05:36:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/about-us\\\/\",\"name\":\"About Us - Class 101 Peachtree City, GA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/#website\"},\"datePublished\":\"2021-05-04T19:05:19+00:00\",\"dateModified\":\"2026-01-20T05:36:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/about-us\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/#website\",\"url\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/\",\"name\":\"Class 101 Peachtree City, GA\",\"description\":\"Just another Class 101 Franchise Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.class101.com\\\/peachtreecityga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us - Class 101 Peachtree City, GA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About Us - Class 101 Peachtree City, GA","og_url":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/","og_site_name":"Class 101 Peachtree City, GA","article_modified_time":"2026-01-20T05:36:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/","url":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/","name":"About Us - Class 101 Peachtree City, GA","isPartOf":{"@id":"https:\/\/www.class101.com\/peachtreecityga\/#website"},"datePublished":"2021-05-04T19:05:19+00:00","dateModified":"2026-01-20T05:36:54+00:00","breadcrumb":{"@id":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.class101.com\/peachtreecityga\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.class101.com\/peachtreecityga\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.class101.com\/peachtreecityga\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/www.class101.com\/peachtreecityga\/#website","url":"https:\/\/www.class101.com\/peachtreecityga\/","name":"Class 101 Peachtree City, GA","description":"Just another Class 101 Franchise Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.class101.com\/peachtreecityga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":0,"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.class101.com\/peachtreecityga\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}